{"id":589,"date":"2021-05-20T18:13:13","date_gmt":"2021-05-20T16:13:13","guid":{"rendered":"https:\/\/anticslfb.com\/?page_id=589"},"modified":"2022-10-11T20:11:31","modified_gmt":"2022-10-11T18:11:31","slug":"miembros","status":"publish","type":"page","link":"https:\/\/anticslfb.com\/es\/miembros\/","title":{"rendered":"Miembros"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.9.2&#8243; background_color=\u00bb#f6f6f6&#8243; custom_padding=\u00bb0px||||false|false\u00bb hover_enabled=\u00bb0&#8243; custom_css_main_element_last_edited=\u00bbon|phone\u00bb sticky_enabled=\u00bb0&#8243; custom_css_main_element_phone=\u00bboverflow: hidden;\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.9.2&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb100%\u00bb max_width=\u00bb2560px\u00bb custom_padding=\u00bb24px||||false|false\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb3.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb]\n  \n  \n\t<script>window.location.replace(\"\/es\/conexion\/?display_alert=true\");<\/script>\n  \n  \n\n\n<div class=\"member-archive-header row\">\n  \n  <div class=\"col-md-6 member-archive-header__content\">\n\n          <!-- Header membres START -->  \n  \n          <h1 class=\"title\">Los miembros<\/h1>\n\n          <div>\n            \u00bfEres antiguo alumno ya registrado? Entra con tu contrase\u00f1a y navega para ver las novedades.\nSi quieres tramitar el alta v\u00eda Web, s\u00f3lo tienes que cumplimentar el siguiente formulario y nos pondremos en contacto contigo lo antes posible.\n          <\/div>\n          <!-- Header membre END -->\n\n  <\/div>\n    \n  \n  <div class=\"col-md-6 member-archive-header__bg-img hide-mobile\" style=\"background: transparent\" id=\"add_background\"><\/div>\n\n<\/div>\n\n\n\n\n\n\n<!-- Filtres START -->\n<div class=\"form-group row member-filter\">\n  <div class=\"col-12\">\n    \n    <div class=\"member-filter__wrapper\">\n      <label for=\"wpv-wpcf-annee-bac\">Filtros<\/label>  \n  \n      <div class=\"member-filter__box\">\n      <select name=\"bac-years\" id=\"bac-years\" onchange=\"addfilter(this, 'bac')\">\n        <option id=\"bac-year_default\" value=\"\">A\u00f1o del bachillerato<\/option>\n        <option id=\"bac-year_1940\" value=\"1940\">1940<\/option>\n        <option id=\"bac-year_1941\" value=\"1941\">1941<\/option>\n        <option id=\"bac-year_1942\" value=\"1942\">1942<\/option>\n        <option id=\"bac-year_1943\" value=\"1943\">1943<\/option>\n        <option id=\"bac-year_1944\" value=\"1944\">1944<\/option>\n        <option id=\"bac-year_1945\" value=\"1945\">1945<\/option>\n        <option id=\"bac-year_1946\" value=\"1946\">1946<\/option>\n        <option id=\"bac-year_1947\" value=\"1947\">1947<\/option>\n        <option id=\"bac-year_1948\" value=\"1948\">1948<\/option>\n        <option id=\"bac-year_1949\" value=\"1949\">1949<\/option>\n        <option id=\"bac-year_1950\" value=\"1950\">1950<\/option>\n        <option id=\"bac-year_1951\" value=\"1951\">1951<\/option>\n        <option id=\"bac-year_1952\" value=\"1952\">1952<\/option>\n        <option id=\"bac-year_1953\" value=\"1953\">1953<\/option>\n        <option id=\"bac-year_1954\" value=\"1954\">1954<\/option>\n        <option id=\"bac-year_1955\" value=\"1955\">1955<\/option>\n        <option id=\"bac-year_1956\" value=\"1956\">1956<\/option>\n        <option id=\"bac-year_1957\" value=\"1957\">1957<\/option>\n        <option id=\"bac-year_1958\" value=\"1958\">1958<\/option>\n        <option id=\"bac-year_1959\" value=\"1959\">1959<\/option>\n        <option id=\"bac-year_1960\" value=\"1960\">1960<\/option>\n        <option id=\"bac-year_1961\" value=\"1961\">1961<\/option>\n        <option id=\"bac-year_1962\" value=\"1962\">1962<\/option>\n        <option id=\"bac-year_1963\" value=\"1963\">1963<\/option>\n        <option id=\"bac-year_1964\" value=\"1964\">1964<\/option>\n        <option id=\"bac-year_1965\" value=\"1965\">1965<\/option>\n        <option id=\"bac-year_1966\" value=\"1966\">1966<\/option>\n        <option id=\"bac-year_1967\" value=\"1967\">1967<\/option>\n        <option id=\"bac-year_1968\" value=\"1968\">1968<\/option>\n        <option id=\"bac-year_1969\" value=\"1969\">1969<\/option>\n        <option id=\"bac-year_1970\" value=\"1970\">1970<\/option>\n        <option id=\"bac-year_1971\" value=\"1971\">1971<\/option>\n        <option id=\"bac-year_1972\" value=\"1972\">1972<\/option>\n        <option id=\"bac-year_1973\" value=\"1973\">1973<\/option>\n        <option id=\"bac-year_1974\" value=\"1974\">1974<\/option>\n        <option id=\"bac-year_1975\" value=\"1975\">1975<\/option>\n        <option id=\"bac-year_1976\" value=\"1976\">1976<\/option>\n        <option id=\"bac-year_1977\" value=\"1977\">1977<\/option>\n        <option id=\"bac-year_1978\" value=\"1978\">1978<\/option>\n        <option id=\"bac-year_1979\" value=\"1979\">1979<\/option>\n        <option id=\"bac-year_1980\" value=\"1980\">1980<\/option>\n        <option id=\"bac-year_1981\" value=\"1981\">1981<\/option>\n        <option id=\"bac-year_1982\" value=\"1982\">1982<\/option>\n        <option id=\"bac-year_1983\" value=\"1983\">1983<\/option>\n        <option id=\"bac-year_1984\" value=\"1984\">1984<\/option>\n        <option id=\"bac-year_1985\" value=\"1985\">1985<\/option>\n        <option id=\"bac-year_1986\" value=\"1986\">1986<\/option>\n        <option id=\"bac-year_1987\" value=\"1987\">1987<\/option>\n        <option id=\"bac-year_1988\" value=\"1988\">1988<\/option>\n        <option id=\"bac-year_1989\" value=\"1989\">1989<\/option>\n        <option id=\"bac-year_1990\" value=\"1990\">1990<\/option>\n        <option id=\"bac-year_1991\" value=\"1991\">1991<\/option>\n        <option id=\"bac-year_1992\" value=\"1992\">1992<\/option>\n        <option id=\"bac-year_1993\" value=\"1993\">1993<\/option>\n        <option id=\"bac-year_1994\" value=\"1994\">1994<\/option>\n        <option id=\"bac-year_1995\" value=\"1995\">1995<\/option>\n        <option id=\"bac-year_1996\" value=\"1996\">1996<\/option>\n        <option id=\"bac-year_1997\" value=\"1997\">1997<\/option>\n        <option id=\"bac-year_1998\" value=\"1998\">1998<\/option>\n        <option id=\"bac-year_1999\" value=\"1999\">1999<\/option>\n        <option id=\"bac-year_2000\" value=\"2000\">2000<\/option>\n        <option id=\"bac-year_2001\" value=\"2001\">2001<\/option>\n        <option id=\"bac-year_2002\" value=\"2002\">2002<\/option>\n        <option id=\"bac-year_2003\" value=\"2003\">2003<\/option>\n        <option id=\"bac-year_2004\" value=\"2004\">2004<\/option>\n        <option id=\"bac-year_2005\" value=\"2005\">2005<\/option>\n        <option id=\"bac-year_2006\" value=\"2006\">2006<\/option>\n        <option id=\"bac-year_2007\" value=\"2007\">2007<\/option>\n        <option id=\"bac-year_2008\" value=\"2008\">2008<\/option>\n        <option id=\"bac-year_2009\" value=\"2009\">2009<\/option>\n        <option id=\"bac-year_2010\" value=\"2010\">2010<\/option>\n        <option id=\"bac-year_2011\" value=\"2011\">2011<\/option>\n        <option id=\"bac-year_2012\" value=\"2012\">2012<\/option>\n        <option id=\"bac-year_2013\" value=\"2013\">2013<\/option>\n        <option id=\"bac-year_2014\" value=\"2014\">2014<\/option>\n        <option id=\"bac-year_2015\" value=\"2015\">2015<\/option>\n        <option id=\"bac-year_2016\" value=\"2016\">2016<\/option>\n        <option id=\"bac-year_2017\" value=\"2017\">2017<\/option>\n        <option id=\"bac-year_2018\" value=\"2018\">2018<\/option>\n        <option id=\"bac-year_2019\" value=\"2019\">2019<\/option>\n        <option id=\"bac-year_2020\" value=\"2020\">2020<\/option>\n        <option id=\"bac-year_2021\" value=\"2021\">2021<\/option>\n        <option id=\"bac-year_2022\" value=\"2022\">2022<\/option>\n        <option id=\"bac-year_2023\" value=\"2023\">2023<\/option>\n        <option id=\"bac-year_2024\" value=\"2024\">2024<\/option>\n        <option id=\"bac-year_2025\" value=\"2025\">2025<\/option>\n        <option id=\"bac-year_2026\" value=\"2026\">2026<\/option>\n        <option id=\"bac-year_2027\" value=\"2027\">2027<\/option>\n        <option id=\"bac-year_2028\" value=\"2028\">2028<\/option>\n        <option id=\"bac-year_2029\" value=\"2029\">2029<\/option>\n        <option id=\"bac-year_2030\" value=\"2030\">2030<\/option>\n      <\/select>\n      <\/div>\n      \n      <div class=\"member-filter__box\">\n      <select name=\"birth-years\" id=\"birth-years\" onchange=\"addfilter(this, 'naissance')\">\n        <option id=\"birth-year_default\" value=\"\">A\u00f1o de nacimiento<\/option>\n        <option id=\"birth-year_1920\" value=\"1920\">1920<\/option>\n        <option id=\"birth-year_1921\" value=\"1921\">1921<\/option>\n        <option id=\"birth-year_1922\" value=\"1922\">1922<\/option>\n        <option id=\"birth-year_1923\" value=\"1923\">1923<\/option>\n        <option id=\"birth-year_1924\" value=\"1924\">1924<\/option>\n        <option id=\"birth-year_1925\" value=\"1925\">1925<\/option>\n        <option id=\"birth-year_1926\" value=\"1926\">1926<\/option>\n        <option id=\"birth-year_1927\" value=\"1927\">1927<\/option>\n        <option id=\"birth-year_1928\" value=\"1928\">1928<\/option>\n        <option id=\"birth-year_1929\" value=\"1929\">1929<\/option>\n        <option id=\"birth-year_1930\" value=\"1930\">1930<\/option>\n        <option id=\"birth-year_1931\" value=\"1931\">1931<\/option>\n        <option id=\"birth-year_1932\" value=\"1932\">1932<\/option>\n        <option id=\"birth-year_1933\" value=\"1933\">1933<\/option>\n        <option id=\"birth-year_1934\" value=\"1934\">1934<\/option>\n        <option id=\"birth-year_1935\" value=\"1935\">1935<\/option>\n        <option id=\"birth-year_1936\" value=\"1936\">1936<\/option>\n        <option id=\"birth-year_1937\" value=\"1937\">1937<\/option>\n        <option id=\"birth-year_1938\" value=\"1938\">1938<\/option>\n        <option id=\"birth-year_1939\" value=\"1938\">1939<\/option>\n        <option id=\"birth-year_1940\" value=\"1940\">1940<\/option>\n        <option id=\"birth-year_1941\" value=\"1941\">1941<\/option>\n        <option id=\"birth-year_1942\" value=\"1942\">1942<\/option>\n        <option id=\"birth-year_1943\" value=\"1943\">1943<\/option>\n        <option id=\"birth-year_1944\" value=\"1944\">1944<\/option>\n        <option id=\"birth-year_1945\" value=\"1945\">1945<\/option>\n        <option id=\"birth-year_1946\" value=\"1946\">1946<\/option>\n        <option id=\"birth-year_1947\" value=\"1947\">1947<\/option>\n        <option id=\"birth-year_1948\" value=\"1948\">1948<\/option>\n        <option id=\"birth-year_1949\" value=\"1949\">1949<\/option>\n        <option id=\"birth-year_1950\" value=\"1950\">1950<\/option>\n        <option id=\"birth-year_1951\" value=\"1951\">1951<\/option>\n        <option id=\"birth-year_1952\" value=\"1952\">1952<\/option>\n        <option id=\"birth-year_1953\" value=\"1953\">1953<\/option>\n        <option id=\"birth-year_1954\" value=\"1954\">1954<\/option>\n        <option id=\"birth-year_1955\" value=\"1955\">1955<\/option>\n        <option id=\"birth-year_1956\" value=\"1956\">1956<\/option>\n        <option id=\"birth-year_1957\" value=\"1957\">1957<\/option>\n        <option id=\"birth-year_1958\" value=\"1958\">1958<\/option>\n        <option id=\"birth-year_1959\" value=\"1959\">1959<\/option>\n        <option id=\"birth-year_1960\" value=\"1960\">1960<\/option>\n        <option id=\"birth-year_1961\" value=\"1961\">1961<\/option>\n        <option id=\"birth-year_1962\" value=\"1962\">1962<\/option>\n        <option id=\"birth-year_1963\" value=\"1963\">1963<\/option>\n        <option id=\"birth-year_1964\" value=\"1964\">1964<\/option>\n        <option id=\"birth-year_1965\" value=\"1965\">1965<\/option>\n        <option id=\"birth-year_1966\" value=\"1966\">1966<\/option>\n        <option id=\"birth-year_1967\" value=\"1967\">1967<\/option>\n        <option id=\"birth-year_1968\" value=\"1968\">1968<\/option>\n        <option id=\"birth-year_1969\" value=\"1969\">1969<\/option>\n        <option id=\"birth-year_1970\" value=\"1970\">1970<\/option>\n        <option id=\"birth-year_1971\" value=\"1971\">1971<\/option>\n        <option id=\"birth-year_1972\" value=\"1972\">1972<\/option>\n        <option id=\"birth-year_1973\" value=\"1973\">1973<\/option>\n        <option id=\"birth-year_1974\" value=\"1974\">1974<\/option>\n        <option id=\"birth-year_1975\" value=\"1975\">1975<\/option>\n        <option id=\"birth-year_1976\" value=\"1976\">1976<\/option>\n        <option id=\"birth-year_1977\" value=\"1977\">1977<\/option>\n        <option id=\"birth-year_1978\" value=\"1978\">1978<\/option>\n        <option id=\"birth-year_1979\" value=\"1979\">1979<\/option>\n        <option id=\"birth-year_1980\" value=\"1980\">1980<\/option>\n        <option id=\"birth-year_1981\" value=\"1981\">1981<\/option>\n        <option id=\"birth-year_1982\" value=\"1982\">1982<\/option>\n        <option id=\"birth-year_1983\" value=\"1983\">1983<\/option>\n        <option id=\"birth-year_1984\" value=\"1984\">1984<\/option>\n        <option id=\"birth-year_1985\" value=\"1985\">1985<\/option>\n        <option id=\"birth-year_1986\" value=\"1986\">1986<\/option>\n        <option id=\"birth-year_1987\" value=\"1987\">1987<\/option>\n        <option id=\"birth-year_1988\" value=\"1988\">1988<\/option>\n        <option id=\"birth-year_1989\" value=\"1989\">1989<\/option>\n        <option id=\"birth-year_1990\" value=\"1990\">1990<\/option>\n        <option id=\"birth-year_1991\" value=\"1991\">1991<\/option>\n        <option id=\"birth-year_1992\" value=\"1992\">1992<\/option>\n        <option id=\"birth-year_1993\" value=\"1993\">1993<\/option>\n        <option id=\"birth-year_1994\" value=\"1994\">1994<\/option>\n        <option id=\"birth-year_1995\" value=\"1995\">1995<\/option>\n        <option id=\"birth-year_1996\" value=\"1996\">1996<\/option>\n        <option id=\"birth-year_1997\" value=\"1997\">1997<\/option>\n        <option id=\"birth-year_1998\" value=\"1998\">1998<\/option>\n        <option id=\"birth-year_1999\" value=\"1999\">1999<\/option>\n        <option id=\"birth-year_2000\" value=\"2000\">2000<\/option>\n        <option id=\"birth-year_2001\" value=\"2001\">2001<\/option>\n        <option id=\"birth-year_2002\" value=\"2002\">2002<\/option>\n        <option id=\"birth-year_2003\" value=\"2003\">2003<\/option>\n        <option id=\"birth-year_2004\" value=\"2004\">2004<\/option>\n        <option id=\"birth-year_2005\" value=\"2005\">2005<\/option>\n        <option id=\"birth-year_2006\" value=\"2006\">2006<\/option>\n        <option id=\"birth-year_2007\" value=\"2007\">2007<\/option>\n        <option id=\"birth-year_2008\" value=\"2008\">2008<\/option>\n        <option id=\"birth-year_2009\" value=\"2009\">2009<\/option>\n        <option id=\"birth-year_2010\" value=\"2010\">2010<\/option>\n        <option id=\"birth-year_2011\" value=\"2011\">2011<\/option>\n        <option id=\"birth-year_2012\" value=\"2012\">2012<\/option>\n        <option id=\"birth-year_2013\" value=\"2013\">2013<\/option>\n        <option id=\"birth-year_2014\" value=\"2014\">2014<\/option>\n        <option id=\"birth-year_2015\" value=\"2015\">2015<\/option>\n        <option id=\"birth-year_2016\" value=\"2016\">2016<\/option>\n        <option id=\"birth-year_2017\" value=\"2017\">2017<\/option>\n        <option id=\"birth-year_2018\" value=\"2018\">2018<\/option>\n        <option id=\"birth-year_2019\" value=\"2019\">2019<\/option>\n        <option id=\"birth-year_2020\" value=\"2020\">2020<\/option>\n        <option id=\"birth-year_2021\" value=\"2021\">2021<\/option>\n        <option id=\"birth-year_2022\" value=\"2022\">2022<\/option>\n        <option id=\"birth-year_2023\" value=\"2023\">2023<\/option>\n        <option id=\"birth-year_2024\" value=\"2024\">2024<\/option>\n        <option id=\"birth-year_2025\" value=\"2025\">2025<\/option>\n        <option id=\"birth-year_2026\" value=\"2026\">2026<\/option>\n        <option id=\"birth-year_2027\" value=\"2027\">2027<\/option>\n        <option id=\"birth-year_2028\" value=\"2028\">2028<\/option>\n        <option id=\"birth-year_2029\" value=\"2029\">2029<\/option>\n        <option id=\"birth-year_2030\" value=\"2030\">2030<\/option>\n      <\/select>\n      <\/div>\n      \n      <div class=\"member-filter__box\">\n      <select name=\"studies\" id=\"studies\" onchange=\"addfilter(this, 'etudes')\">\n        <option id=\"studies_default\" value=\"\">Estudios<\/option>\n        <option id=\"studies_admin_dir\" value=\"admin_dir\">Administration et direction d'entreprises<\/option>\n        <option id=\"studies_admin_publique\" value=\"admin_publique\">Administration publique<\/option>\n        <option id=\"studies_anthropologie\" value=\"anthropologie\">Anthropologie<\/option>\n        <option id=\"studies_sciences_politiques\" value=\"sciences_politiques\">Sciences politiques<\/option>\n        <option id=\"studies_commerce\" value=\"commerce\">Commerce<\/option>\n        <option id=\"studies_com_audiovisuelle\" value=\"com_audiovisuelle\">Communication audiovisuelle<\/option>\n        <option id=\"studies_criminologie\" value=\"criminologie\">Criminologie<\/option>\n        <option id=\"studies_edu_physique\" value=\"edu_physique\">\u00c9ducation physique<\/option>\n        <option id=\"studies_droit\" value=\"droit\">Droit<\/option>\n        <option id=\"studies_economie\" value=\"economie\">\u00c9conomie<\/option>\n        <option id=\"studies_enseignement\" value=\"enseignement\">Enseignement<\/option>\n        <option id=\"studies_finance\" value=\"finance\">Finance<\/option>\n        <option id=\"studies_marketing\" value=\"marketing\">Marketing<\/option>\n        <option id=\"studies_journalisme\" value=\"journalisme\">Journalisme<\/option>\n        <option id=\"studies_psychologie\" value=\"psychologie\">Psychologie<\/option>\n        <option id=\"studies_pub_rp\" value=\"pub_rp\">Publicit\u00e9 et relations publiques<\/option>\n        <option id=\"studies_rh\" value=\"rh\">Ressources humaines<\/option>\n        <option id=\"studies_ri\" value=\"ri\">Relations internationales<\/option>\n        <option id=\"studies_sociologie\" value=\"sociologie\">Sociologie<\/option>\n        <option id=\"studies_social\" value=\"social\">Travail social<\/option>\n        <option id=\"studies_tourisme\" value=\"tourisme\">Tourisme<\/option>\n        <option id=\"studies_architecture\" value=\"architecture\">Architecture<\/option>\n        <option id=\"studies_inge_aero\" value=\"inge_aero\">Ing\u00e9nierie a\u00e9ronautique<\/option>\n        <option id=\"studies_inge_agri\" value=\"inge_agri\">Ing\u00e9nierie  agricole<\/option>\n        <option id=\"studies_tp\" value=\"tp\">Travaux publics<\/option>\n        <option id=\"studies_mat\" value=\"mat\">Ing\u00e9nierie des mat\u00e9riaux<\/option>\n        <option id=\"studies_telecom\" value=\"telecom\">Ing\u00e9nierie des T\u00e9l\u00e9communications<\/option>\n        <option id=\"studies_son-img\" value=\"son-img\">Ing\u00e9nierie du son et de l'image<\/option>\n        <option id=\"studies_elec\" value=\"elec\">Ing\u00e9nieur \u00e9lectrique<\/option>\n        <option id=\"studies_foret\" value=\"foret\">Ing\u00e9nierie foresti\u00e8re<\/option>\n        <option id=\"studies_geo\" value=\"geo\">Ing\u00e9nierie g\u00e9ologique<\/option>\n        <option id=\"studies_indu\" value=\"indu\">Ing\u00e9nierie Industrielle<\/option>\n        <option id=\"studies_it\" value=\"it\">Ing\u00e9nierie informatique<\/option>\n        <option id=\"studies_maritime\" value=\"maritime\">Ing\u00e9nierie maritime<\/option>\n        <option id=\"studies_nautique\" value=\"nautique\">Ing\u00e9nierie nautique<\/option>\n        <option id=\"studies_inge_chimie\" value=\"inge_chimie\">Ing\u00e9nierie chimique<\/option>\n        <option id=\"studies_textile\" value=\"textile\">Ing\u00e9nierie textile<\/option>\n        <option id=\"studies_multim\u00e9dia\" value=\"multim\u00e9dia\">Multim\u00e9dia<\/option>\n        <option id=\"studies_pilote\" value=\"pilote\">Pilote d'aviation commerciale<\/option>\n        <option id=\"studies_archeologie\" value=\"archeologie\">Arch\u00e9ologie<\/option>\n        <option id=\"studies_arts\" value=\"arts\">Beaux Arts<\/option>\n        <option id=\"studies_cinema\" value=\"cinema\">Cin\u00e9ma<\/option>\n        <option id=\"studies_danse\" value=\"danse\">Danse<\/option>\n        <option id=\"studies_conception\" value=\"conception\">Conception<\/option>\n        <option id=\"studies_design\" value=\"design\">Design d'int\u00e9rieur<\/option>\n        <option id=\"studies_litterature\" value=\"litterature\">\u00c9tudes litt\u00e9raires<\/option>\n        <option id=\"studies_philo\" value=\"philo\">Philosophie<\/option>\n        <option id=\"studies_photo\" value=\"photo\">Photographie<\/option>\n        <option id=\"studies_geographie\" value=\"geographie\">G\u00e9ographie<\/option>\n        <option id=\"studies_histoire\" value=\"histoire\">Histoire<\/option>\n        <option id=\"studies_histoire_art\" value=\"histoire_art\">Histoire de l'art<\/option>\n        <option id=\"studies_histoire_musique\" value=\"histoire_musique\">Histoire et sciences de la musique<\/option>\n        <option id=\"studies_sciences_humaines\" value=\"sciences_humaines\">Sciences humaines<\/option>\n        <option id=\"studies_anglais\" value=\"anglais\">Langue Anglaise<\/option>\n        <option id=\"studies_fran\u00e7ais\" value=\"fran\u00e7ais\">Langue Fran\u00e7aise<\/option>\n        <option id=\"studies_espagnol\" value=\"espagnol\">Langue Espagnole<\/option>\n        <option id=\"studies_catalan\" value=\"catalan\">Langue Catalane<\/option>\n        <option id=\"studies_langues_modernes\" value=\"langues_modernes\">Langues modernes<\/option>\n        <option id=\"studies_langue_litte\" value=\"langue_litte\">Langues et litt\u00e9ratures classiques<\/option>\n        <option id=\"studies_langues_appliquees\" value=\"langues_appliquees\">Linguistique et langues appliqu\u00e9es<\/option>\n        <option id=\"studies_musique\" value=\"musique\">Musique<\/option>\n        <option id=\"studies_theatre\" value=\"theatre\">Th\u00e9\u00e2tre<\/option>\n        <option id=\"studies_theatre\" value=\"traduction\">Traduction<\/option>\n        <option id=\"studies_philologie\" value=\"philologie\">Philologie<\/option>\n        <option id=\"studies_alimentaire\" value=\"alimentaire\">Sciences et technologies alimentaires<\/option>\n        <option id=\"studies_biomedicale\" value=\"biomedicale\">Sciences biomedicales<\/option>\n        <option id=\"studies_infirmerie\" value=\"infirmerie\">Infirmerie<\/option>\n        <option id=\"studies_pharmacie\" value=\"pharmacie\">Pharmacie<\/option>\n        <option id=\"studies_physio\" value=\"physio\">Physioth\u00e9rapie<\/option>\n        <option id=\"studies_inge_biomedicale\" value=\"inge_biomedicale\">Ing\u00e9nierie biom\u00e9dicale<\/option>\n        <option id=\"studies_orthophonie\" value=\"orthophonie\">Orthophonie<\/option>\n        <option id=\"studies_medecine\" value=\"medecine\">M\u00e9decine<\/option>\n        <option id=\"studies_nutrition\" value=\"nutrition\">Nutrition et di\u00e9t\u00e9tique<\/option>\n        <option id=\"studies_odontologie\" value=\"odontologie\">Odontologie<\/option>\n        <option id=\"studies_podologie\" value=\"podologie\">Podologie<\/option>\n        <option id=\"studies_veterinaire\" value=\"veterinaire\">V\u00e9t\u00e9rinaire<\/option>\n        <option id=\"studies_biologie\" value=\"biologie\">Biologie<\/option>\n        <option id=\"studies_biochimie\" value=\"biochimie\">Biochimie<\/option>\n        <option id=\"studies_biotechnologie\" value=\"biotechnologie\">Biotechnologie<\/option>\n        <option id=\"studies_environnement\" value=\"environnement\">Sciences de l'environnement<\/option>\n        <option id=\"studies_sciences_mer\" value=\"sciences_mer\">Sciences de la mer<\/option>\n        <option id=\"studies_oenologie\" value=\"oenologie\">Oenologie<\/option>\n        <option id=\"studies_statistiques\" value=\"statistiques\">Statistiques<\/option>\n        <option id=\"studies_physique\" value=\"physique\">Physique<\/option>\n        <option id=\"studies_genetique\" value=\"genetique\">G\u00e9n\u00e9tique<\/option>\n        <option id=\"studies_geologie\" value=\"geologie\">G\u00e9ologie<\/option>\n        <option id=\"studies_math\" value=\"math\">Math\u00e9matiques<\/option>\n        <option id=\"studies_optique\" value=\"optique\">Optique et optom\u00e9trie<\/option>\n        <option id=\"studies_chimie\" value=\"chimie\">Chimie<\/option>\n      <\/select>\n      <\/div>\n      \n      <div class=\"member-filter__box\">\n      <select name=\"job\" id=\"job\" onchange=\"addfilter(this, 'profession')\">\n        <option id=\"job_default\" value=\"\">Profesi\u00f3n<\/option>\n        <option id=\"job_1\" value=\"1\">Abogado<\/option>\n        <option id=\"job_2\" value=\"2\">Actor<\/option>\n        <option id=\"job_3\" value=\"3\">Administrativo<\/option>\n        <option id=\"job_4\" value=\"4\">Agr\u00f3nomo<\/option>\n        <option id=\"job_5\" value=\"5\">Arque\u00f3logo<\/option>\n        <option id=\"job_6\" value=\"6\">Arquitecto<\/option>\n        <option id=\"job_7\" value=\"7\">Artista<\/option>\n        <option id=\"job_8\" value=\"8\">Asesor<\/option>\n        <option id=\"job_9\" value=\"9\">Atleta<\/option>\n        <option id=\"job_10\" value=\"10\">Bi\u00f3logo<\/option>\n        <option id=\"job_11\" value=\"11\">Bioqu\u00edmico<\/option>\n        <option id=\"job_12\" value=\"12\">Conserje<\/option>\n        <option id=\"job_13\" value=\"13\">Consultor<\/option>\n        <option id=\"job_14\" value=\"14\">Dibujante<\/option>\n        <option id=\"job_15\" value=\"15\">Enfermero<\/option>\n        <option id=\"job_16\" value=\"16\">Escritor<\/option>\n        <option id=\"job_17\" value=\"17\">Farmac\u00e9utico<\/option>\n        <option id=\"job_18\" value=\"18\">Fil\u00f3sofo<\/option>\n        <option id=\"job_19\" value=\"19\">Fiscal<\/option>\n        <option id=\"job_20\" value=\"20\">F\u00edsic<\/option>\n        <option id=\"job_21\" value=\"21\">Fisioterapeuta<\/option>\n        <option id=\"job_22\" value=\"22\">Fot\u00f3grafo<\/option>\n        <option id=\"job_23\" value=\"23\">Gerente<\/option>\n        <option id=\"job_24\" value=\"24\">Gestor<\/option>\n        <option id=\"job_25\" value=\"25\">Inform\u00e1tico<\/option>\n        <option id=\"job_26\" value=\"26\">Ingeniero<\/option>\n        <option id=\"job_27\" value=\"27\">Investigador<\/option>\n        <option id=\"job_28\" value=\"28\">Jardinero<\/option>\n        <option id=\"job_29\" value=\"29\">Juez<\/option>\n        <option id=\"job_30\" value=\"30\">Ling\u00fcista<\/option>\n        <option id=\"job_31\" value=\"31\">Marketing<\/option>\n        <option id=\"32\" value=\"32\">Matem\u00e1tico<\/option>\n        <option id=\"job_33\" value=\"33\">M\u00e9dico<\/option>\n        <option id=\"job_34\" value=\"34\">Paleont\u00f3logo<\/option>\n        <option id=\"job_35\" value=\"35\">Periodista<\/option>\n        <option id=\"job_36\" value=\"36\">Perito<\/option>\n        <option id=\"job_37\" value=\"37\">Pintor<\/option>\n        <option id=\"job_38\" value=\"38\">Polic\u00eda<\/option>\n        <option id=\"job_39\" value=\"39\">Professor<\/option>\n        <option id=\"job_40\" value=\"40\">Psic\u00f3logo<\/option>\n        <option id=\"job_41\" value=\"41\">Publicista<\/option>\n        <option id=\"job_42\" value=\"42\">Qu\u00edmico<\/option>\n        <option id=\"job_43\" value=\"43\">Te\u00f3logo<\/option>\n        <option id=\"job_44\" value=\"44\">Traductor<\/option>\n        <option id=\"job_45\" value=\"45\">Veterinario<\/option>\n        <option id=\"job_46\" value=\"46\">Otros<\/option>\n      <\/select>\n      <\/div>\n      \n    <\/div>\n    \n    \n<\/div>  \n<\/div>\n\n  <div class=\"row member-filter_search\">\n    <div class=\"col-12\">\n      <form id=\"member-filter__form\">\n      <div class=\"member-filter__wrapper member-filter__id-search\">\n        \n        <div class=\"member-filter__box\">\n          <label for=\"fisrtname\">Nombre<\/label>\n          <input type=\"text\" id=\"firstname\" name=\"firstname\">\n        <\/div>\n      \n        <div class=\"member-filter__box\">\n          <label for=\"lastname\">Apellido<\/label>\n          <input type=\"text\" id=\"lastname\" name=\"lastname\">\n        <\/div> \n      \n        <div class=\"member-filter__btn-wrapper\">  \n        <div class=\"member-filter__box\">\n          <button type=\"submit\" class=\"member-filter__btn\">Buscar<\/button>\n        <\/div>  \n        \n       <div class=\"member-filter__box\">\n          <button type=\"button\" class=\"member-filter__btn\" id=\"member-filter__reset-btn\">Restablecer<\/button>\n       <\/div>\n     <\/div>\n        \n    <\/div>\n    <\/form> \n    <\/div>\n  <\/div>\n<!-- Filtres END -->\n\n<div class=\"member-archive\">\n<div class=\"container\">\n\n\t\n  \t<div style=\"display:none\" class=\"member-loop-item row\">\n\t\n\t\t\n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Dolors&#038;lastname=Gonz\u00e1lez Juan\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Dolors&#038;lastname=Gonz\u00e1lez Juan\">Dolors Gonz\u00e1lez Juan<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Mila&#038;lastname=Flores Sauvage\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Mila&#038;lastname=Flores Sauvage\">Mila Flores Sauvage<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Ciencias Pol\u00edticas<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Sara&#038;lastname=Flores Sauvage\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Sara&#038;lastname=Flores Sauvage\">Sara Flores Sauvage<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Ciencias Pol\u00edticas<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1991<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Luis&#038;lastname=D\u00edaz\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Luis&#038;lastname=D\u00edaz\">Luis D\u00edaz<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1972\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=montserrat&#038;lastname=CALVET PIN\u00d3S\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=montserrat&#038;lastname=CALVET PIN\u00d3S\">montserrat CALVET PIN\u00d3S<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1954\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('https:\/\/anticslfb.com\/wp-content\/uploads\/2023\/10\/Dr.-Llui\u0301s-Puig-Alta38.jpg')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1985<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Llu\u00eds&#038;lastname=Puig Verdi\u00e9\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Llu\u00eds&#038;lastname=Puig Verdi\u00e9\">Llu\u00eds Puig Verdi\u00e9<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1967\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Medicina<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">UAB<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">M\u00e9dico<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Hospital del Mar - Quironsalud<\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1982<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Teresa&#038;lastname=Basilio\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Teresa&#038;lastname=Basilio\">Teresa Basilio<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1964\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Carlos&#038;lastname=Pascual Gal\u00e1n\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Carlos&#038;lastname=Pascual Gal\u00e1n\">Carlos Pascual Gal\u00e1n<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Hakon&#038;lastname=Tonner Garcia\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Hakon&#038;lastname=Tonner Garcia\">Hakon Tonner Garcia<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Humanidades<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Alexandre&#038;lastname=Alandry\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Alexandre&#038;lastname=Alandry\">Alexandre Alandry<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administraci\u00f3n y Direcci\u00f3n de Empresas<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2005<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Anna&#038;lastname=And\u00eda Adroher\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Anna&#038;lastname=And\u00eda Adroher\">Anna And\u00eda Adroher<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1987\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2005<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Alba&#038;lastname=Ambr\u00f3s Coso\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Alba&#038;lastname=Ambr\u00f3s Coso\">Alba Ambr\u00f3s Coso<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1985\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Anna Burgues&#038;lastname=Torra\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Anna Burgues&#038;lastname=Torra\">Anna Burgues Torra<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('https:\/\/anticslfb.com\/wp-content\/uploads\/2024\/10\/AB.png')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1978<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Albert&#038;lastname=Bolea\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Albert&#038;lastname=Bolea\">Albert Bolea<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1959\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Turismo<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">CETT<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Fot\u00f3grafo<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Travelab Spain<\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2021<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"https:\/\/www.linkedin.com\/in\/abigael-genetre-7627a6241?utm_source=share&#038;utm_campaign=share_via&#038;utm_content=profile&#038;utm_medium=ios_app\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Abigael&#038;lastname=Genetre\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Abigael&#038;lastname=Genetre\">Abigael Genetre<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2004\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1992<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=abigail&#038;lastname=l\u00f3pez\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=abigail&#038;lastname=l\u00f3pez\">abigail l\u00f3pez<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2000<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Abigail&#038;lastname=Serrate\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Abigail&#038;lastname=Serrate\">Abigail Serrate<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1981\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1977<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Blasco&#038;lastname=Albert\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Blasco&#038;lastname=Albert\">Blasco Albert<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1959\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Magisterio<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">UAB<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Otros<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Abril&#038;lastname=Gonz\u00e1lez Ricardo\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Abril&#038;lastname=Gonz\u00e1lez Ricardo\">Abril Gonz\u00e1lez Ricardo<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administraci\u00f3n y Direcci\u00f3n de Empresas<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Anabel&#038;lastname=Casahuga Montserrat\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Anabel&#038;lastname=Casahuga Montserrat\">Anabel Casahuga Montserrat<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1972\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1990<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Alexandre&#038;lastname=Casanovas Lepreux\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Alexandre&#038;lastname=Casanovas Lepreux\">Alexandre Casanovas Lepreux<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1971\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administraci\u00f3n y Direcci\u00f3n de Empresas<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Universitat de Barcelona<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Marketing<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Atrevia<\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Albert&#038;lastname=Cobos\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Albert&#038;lastname=Cobos\">Albert Cobos<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1958\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('https:\/\/anticslfb.com\/wp-content\/uploads\/2024\/11\/per.jpg')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1995<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=albert&#038;lastname=comerma pi\u00f1a\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=albert&#038;lastname=comerma pi\u00f1a\">albert comerma pi\u00f1a<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1977\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Arquitectura<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">UPC - ETSAB<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Arquitecto<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">www.maap.cat<\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adolfo&#038;lastname=Corvinos\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adolfo&#038;lastname=Corvinos\">Adolfo Corvinos<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1974\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adam&#038;lastname=Mezghani\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adam&#038;lastname=Mezghani\">Adam Mezghani<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Ingenier\u00eda Inform\u00e1tica<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1989<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Ada&#038;lastname=Moya\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Ada&#038;lastname=Moya\">Ada Moya<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1972\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2024<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adela&#038;lastname=Macho\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adela&#038;lastname=Macho\">Adela Macho<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2006\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adeline&#038;lastname=Paulian\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adeline&#038;lastname=Paulian\">Adeline Paulian<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adelaida&#038;lastname=Trias\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adelaida&#038;lastname=Trias\">Adelaida Trias<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2006<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adelaida&#038;lastname=Trias\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adelaida&#038;lastname=Trias\">Adelaida Trias<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1986\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Psicolog\u00eda<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Blanquerna<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Psic\u00f3logo<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('IMG_4227.jpeg')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2006<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"https:\/\/www.linkedin.com\/in\/adrianlatorre\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adrian&#038;lastname=Latorre\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adrian&#038;lastname=Latorre\">Adrian Latorre<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1988\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Ingenier\u00eda de Telecomunicaciones<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">UPC<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Inform\u00e1tico<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Adyen <\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=adria&#038;lastname=lopez rosell\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=adria&#038;lastname=lopez rosell\">adria lopez rosell<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1990<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Sala de Vedruna\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Sala de Vedruna\">Adriana Sala de Vedruna<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1972\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2004<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=ADRIANA&#038;lastname=AYMAM\u00cd GARC\u00c9S\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=ADRIANA&#038;lastname=AYMAM\u00cd GARC\u00c9S\">ADRIANA AYMAM\u00cd GARC\u00c9S<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1986\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1980<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Sala De Vedruna\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Sala De Vedruna\">Adriana Sala De Vedruna<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1972\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">M\u00e9dico<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1992<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=adrian&#038;lastname=wegrzyn\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=adrian&#038;lastname=wegrzyn\">adrian wegrzyn<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1974\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Cousin Diego\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Cousin Diego\">Adriana Cousin Diego<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Ingenier\u00eda Industrial<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2016<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=adrien&#038;lastname=guy\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=adrien&#038;lastname=guy\">adrien guy<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1998\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administrativo<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=adrien&#038;lastname=saenz cordon\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=adrien&#038;lastname=saenz cordon\">adrien saenz cordon<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2010<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Lopez\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Adriana&#038;lastname=Lopez\">Adriana Lopez<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1992\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2024<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Agata&#038;lastname=Martin\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Agata&#038;lastname=Martin\">Agata Martin<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2006\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Ingenier\u00eda Qu\u00edmica<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2021<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Agatha &#038;lastname=Arcos\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Agatha &#038;lastname=Arcos\">Agatha  Arcos<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2003\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2026<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Agatha&#038;lastname=Kobrak Andino\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Agatha&#038;lastname=Kobrak Andino\">Agatha Kobrak Andino<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2008\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Relaciones internacionales<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('https:\/\/anticslfb.com\/wp-content\/uploads\/2023\/12\/IMG_20231207_171316-1.jpg')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1994<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Agata&#038;lastname=Gatell\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Agata&#038;lastname=Gatell\">Agata Gatell<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1976\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administraci\u00f3n y Direcci\u00f3n de Empresas<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Eadi <\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administrativo<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Winther<\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('https:\/\/anticslfb.com\/wp-content\/uploads\/2023\/12\/IMG_20231207_171316.jpg')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1993<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Agata&#038;lastname=Cano \" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Agata&#038;lastname=Cano \">Agata Cano <\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1975\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administraci\u00f3n P\u00fablica<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">ANC<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Administrativo<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Axa<\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('https:\/\/anticslfb.com\/wp-content\/uploads\/2024\/03\/4FAA77F1-B63F-4CD1-BD9F-99202FC6FB34.jpeg')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">2021<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Agathe&#038;lastname=Michel \" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Agathe&#038;lastname=Michel \">Agathe Michel <\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 2003\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Medicina<\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">Universit\u00e9 Claude Bernard Lyon 1<\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\">Otros<\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\">pas d\u2019entreprise <\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\"><\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=Alexandra&#038;lastname=Gelabert\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=Alexandra&#038;lastname=Gelabert\">Alexandra Gelabert<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : \n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n          <div class=\"col-12 col-md-4 col-lg-3 member-item\">\n            Perfil professeurs\n\n<div class=\"member__content_item-wrapper\">\n<!-- Profil info START -->  \n<div class=\"member__content\" style=\"background:url('')\">\n  \t\n  \n  \t<div class=\"member__content-wrapper\">\n      \n      <!-- Top info START -->\n    \t<div class=\"member__content-details-top\">\n          <h2 class=\"title\">1987<\/h2>\n          \n          <div class=\"member__content-details-top-links\">\n            \n            <div class=\"member__content-linkedin hovered\">\n              <a href=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/linkedin-icon.svg\" alt=\"linkedin icon\"><\/a>\n            <\/div>\n            \n            <div class=\"plus__content-wrapper\">  \n \t\t\t\t<a href=\"\/fiche-membre\/?firstname=AGNES&#038;lastname=RIVERA AUSTRUI\" class=\"plus__content-post-link hovered\">\n       \t\t\t<img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/Plus.svg\" alt=\"plus icon\">\n    \t\t\t<\/a>\n   \t\t    <\/div>\n            \n          <\/div> \n            \n         <\/div> \n        <!-- Top info END -->\n          \n        \n        <!-- Bottom info START -->\n        <div class=\"member__content-details-bottom\">\n          <h3 class=\"title\">\n            <a class=\"hovered\" href=\"\/fiche-membre\/?firstname=AGNES&#038;lastname=RIVERA AUSTRUI\">AGNES RIVERA AUSTRUI<\/a>\n          <\/h3>\n          \n          <div class=\"member__content-birth-info\">\n            Nacimiento : 1969\n          <\/div>\n        <\/div>  \n        <!-- Bottom info END -->  \n          \n     <\/div>          \n <\/div>         \n<!-- Profil info END -->\n\n<!-- Studies and job info START -->\n<div class=\"member-pro-info__wrapper\">\n  \n  <div class=\"member-school-info__wrapper\">\n    \n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/school-icon.svg\" alt=\"school icon\">\n    <\/div>\n    \n    <div class=\"member-school-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>\n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>  \n  \n  <div class=\"member__content-divider\"><\/div>\n  \n  <div class=\"member-job-info__wrapper\">\n    <div>\n      <img decoding=\"async\" src=\"https:\/\/anticslfb.com\/wp-content\/uploads\/2021\/05\/job-icon.svg\" alt=\"job icon\">\n    <\/div>\n    \n    <div class=\"member-job-details__wrapper\">\n      <div class=\"membre-pro-first-data\"><\/div>  \n    <\/div>  \n    \n  <\/div>\n  \n  <div class=\"membre-pro-second-data\"><\/div>\n  \n<\/div>  \n<!-- Studies and job info END -->\n<!-- Profil info END -->\n<\/div>  \n          <\/div>  \n\t\t\n         \n\t\n    <\/div>\n\t\n  \t<div id=\"view_count\" data-qty=\"2766\"><\/div>\n\t\n \n<\/div> \n<\/div> \n\n\n<div class=\"membres-pagination\" style=\"display:none\">\n<select name=\"pagination\" id=\"page-select\" onchange=\"paginate(this)\">\n<\/select>\n<\/div>\n [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.9.2&#8243; background_color=\u00bb#f6f6f6&#8243; custom_padding=\u00bb0px||||false|false\u00bb hover_enabled=\u00bb0&#8243; custom_css_main_element_last_edited=\u00bbon|phone\u00bb sticky_enabled=\u00bb0&#8243; custom_css_main_element_phone=\u00bboverflow: hidden;\u00bb][et_pb_row admin_label=\u00bbrow\u00bb _builder_version=\u00bb4.9.2&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb100%\u00bb max_width=\u00bb2560px\u00bb custom_padding=\u00bb24px||||false|false\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb3.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb][\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"author":1,"featured_media":3493,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[wpv-view name=\"membres-archive\"]","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"class_list":["post-589","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/pages\/589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/comments?post=589"}],"version-history":[{"count":10,"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/pages\/589\/revisions"}],"predecessor-version":[{"id":3516,"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/pages\/589\/revisions\/3516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/media\/3493"}],"wp:attachment":[{"href":"https:\/\/anticslfb.com\/es\/wp-json\/wp\/v2\/media?parent=589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}